{"id":119645,"date":"2025-09-25T21:15:54","date_gmt":"2025-09-25T18:15:54","guid":{"rendered":"https:\/\/myfitnessbag.com\/?post_type=product&#038;p=119645"},"modified":"2026-04-27T18:25:22","modified_gmt":"2026-04-27T15:25:22","slug":"%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86","status":"publish","type":"product","link":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/","title":{"rendered":"\u0631\u0646 \u0623\u0644\u0648\u0646 \u0646\u0648\u062a\u0631\u064a\u0634\u0646 \u0648\u0627\u064a \u0631\u0646"},"content":{"rendered":"<h2 style=\"text-align: right\" data-path-to-node=\"2\"><b data-path-to-node=\"2\" data-index-in-node=\"0\">\u0631\u0646 \u0623\u0644\u0648\u0646 \u0646\u0648\u062a\u0631\u064a\u0634\u0646 \u0648\u0627\u064a \u0631\u0646 (Run Alone Whey Run)<\/b><\/h2>\n<p style=\"text-align: right\" data-path-to-node=\"3\"><b data-path-to-node=\"3\" data-index-in-node=\"0\">1.05 \u0643\u062c\u0645 | 30 \u062d\u0635\u0629 \u062a\u062f\u0631\u064a\u0628\u064a\u0629 | \u0646\u0643\u0647\u0629 \u0643\u0648\u0643\u0648 \u0628\u064a\u0633\u0643\u0648 (Coco Bisco)<\/b><\/p>\n<p style=\"text-align: right\" data-path-to-node=\"4\">\u0627\u0631\u0641\u0639 \u0645\u0633\u062a\u0648\u0649 \u0623\u062f\u0627\u0626\u0643 \u0645\u0639 \u0628\u0631\u0648\u062a\u064a\u0646 <b data-path-to-node=\"4\" data-index-in-node=\"27\">WHEY RUN<\/b>\u061b \u0627\u0644\u0645\u0632\u064a\u062c \u0627\u0644\u0645\u062a\u0642\u062f\u0645 \u0627\u0644\u0645\u0635\u0645\u0645 \u062e\u0635\u064a\u0635\u0627\u064b \u0644\u0644\u0631\u064a\u0627\u0636\u064a\u064a\u0646 \u0627\u0644\u0630\u064a\u0646 \u064a\u0628\u062d\u062b\u0648\u0646 \u0639\u0646 \u0627\u0644\u0623\u0641\u0636\u0644. \u062a\u0648\u0641\u0631 \u0647\u0630\u0647 \u0627\u0644\u062a\u0631\u0643\u064a\u0628\u0629 24 \u062c\u0631\u0627\u0645\u0627\u064b \u0645\u0646 \u0627\u0644\u0628\u0631\u0648\u062a\u064a\u0646 \u0644\u0643\u0644 \u062d\u0635\u0629 \u0644\u062f\u0639\u0645 \u0627\u0644\u0627\u0633\u062a\u0634\u0641\u0627\u0621 \u0627\u0644\u0633\u0631\u064a\u0639\u060c \u0628\u0646\u0627\u0621 \u0627\u0644\u0639\u0636\u0644\u0627\u062a \u0627\u0644\u0635\u0627\u0641\u064a\u0629\u060c \u0648\u062a\u0639\u0632\u064a\u0632 \u0627\u0644\u0642\u0648\u0629 \u0627\u0644\u0628\u062f\u0646\u064a\u0629 \u0628\u0639\u062f \u0627\u0644\u062a\u0645\u0627\u0631\u064a\u0646 \u0627\u0644\u0634\u0627\u0642\u0629.<\/p>\n<h3 style=\"text-align: right\" data-path-to-node=\"5\"><b data-path-to-node=\"5\" data-index-in-node=\"0\">\u0623\u0628\u0631\u0632 \u0627\u0644\u0645\u0645\u064a\u0632\u0627\u062a:<\/b><\/h3>\n<ul style=\"text-align: right\" data-path-to-node=\"6\">\n<li>\n<p data-path-to-node=\"6,0,0\"><b data-path-to-node=\"6,0,0\" data-index-in-node=\"0\">\u0645\u0632\u064a\u062c \u0648\u0627\u064a \u0628\u0631\u0648\u062a\u064a\u0646 \u0645\u062a\u0637\u0648\u0631:<\/b> \u062a\u0631\u0643\u064a\u0628\u0629 \u0642\u0648\u064a\u0629 \u062a\u062c\u0645\u0639 \u0628\u064a\u0646 (\u0627\u0644\u0648\u0627\u064a \u0628\u0631\u0648\u062a\u064a\u0646 \u0643\u0648\u0646\u0633\u0646\u062a\u0631\u064a\u062a\u060c \u0648\u0627\u0644\u0622\u064a\u0632\u0648\u0644\u064a\u062a\u060c \u0648\u0627\u0644\u0647\u064a\u062f\u0631\u0648\u0644\u064a\u0632\u064a\u062f) \u0644\u0636\u0645\u0627\u0646 \u0623\u0642\u0635\u0649 \u062f\u0631\u062c\u0627\u062a \u0627\u0644\u0627\u0645\u062a\u0635\u0627\u0635.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"6,1,0\"><b data-path-to-node=\"6,1,0\" data-index-in-node=\"0\">\u062f\u0639\u0645 \u0628\u0646\u0627\u0621 \u0627\u0644\u0639\u0636\u0644\u0627\u062a \u0627\u0644\u0635\u0627\u0641\u064a\u0629:<\/b> \u064a\u0645\u062f \u062c\u0633\u0645\u0643 \u0628\u0627\u0644\u0623\u062d\u0645\u0627\u0636 \u0627\u0644\u0623\u0645\u064a\u0646\u064a\u0629 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629 \u0627\u0644\u0644\u0627\u0632\u0645\u0629 \u0644\u0628\u0646\u0627\u0621 \u0627\u0644\u0623\u0646\u0633\u062c\u0629 \u0627\u0644\u0639\u0636\u0644\u064a\u0629 \u0648\u0627\u0644\u062d\u0641\u0627\u0638 \u0639\u0644\u064a\u0647\u0627.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"6,2,0\"><b data-path-to-node=\"6,2,0\" data-index-in-node=\"0\">\u0627\u0633\u062a\u0634\u0641\u0627\u0621 \u0633\u0631\u064a\u0639:<\/b> \u064a\u0633\u0627\u0639\u062f \u0641\u064a \u062a\u0631\u0645\u064a\u0645 \u0627\u0644\u0623\u0644\u064a\u0627\u0641 \u0627\u0644\u0639\u0636\u0644\u064a\u0629 \u0627\u0644\u0645\u062c\u0647\u062f\u0629 \u0648\u062a\u0642\u0644\u064a\u0644 \u0648\u0642\u062a \u0627\u0644\u0631\u0627\u062d\u0629 \u0628\u064a\u0646 \u0627\u0644\u062d\u0635\u0635 \u0627\u0644\u062a\u062f\u0631\u064a\u0628\u064a\u0629.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"6,3,0\"><b data-path-to-node=\"6,3,0\" data-index-in-node=\"0\">\u0637\u0639\u0645 \u063a\u0646\u064a \u0648\u0628\u062f\u0648\u0646 \u0634\u0639\u0648\u0631 \u0628\u0627\u0644\u0630\u0646\u0628:<\/b> \u0646\u0643\u0647\u0629 \u0628\u0633\u0643\u0648\u064a\u062a \u0627\u0644\u0634\u0648\u0643\u0648\u0644\u0627\u062a\u0629 \u0627\u0644\u0631\u0627\u0626\u0639\u0629 \u0645\u0639 <b data-path-to-node=\"6,3,0\" data-index-in-node=\"61\">0 \u062c\u0631\u0627\u0645 \u0633\u0643\u0631 \u0645\u0636\u0627\u0641<\/b>\u060c \u0645\u0645\u0627 \u064a\u062c\u0639\u0644\u0647 \u0627\u0644\u0645\u0643\u0627\u0641\u0623\u0629 \u0627\u0644\u0645\u062b\u0627\u0644\u064a\u0629 \u0628\u0639\u062f \u0627\u0644\u062a\u0645\u0631\u064a\u0646.<\/p>\n<\/li>\n<\/ul>\n<hr data-path-to-node=\"7\" \/>\n<h3 style=\"text-align: right\" data-path-to-node=\"8\"><b data-path-to-node=\"8\" data-index-in-node=\"0\">\u062d\u0642\u0627\u0626\u0642 \u0627\u0644\u062a\u063a\u0630\u064a\u0629 (\u0644\u0643\u0644 \u062d\u0635\u0629 &#8211; 35 \u062c\u0631\u0627\u0645):<\/b><\/h3>\n<ul style=\"text-align: right\" data-path-to-node=\"9\">\n<li>\n<p data-path-to-node=\"9,0,0\"><b data-path-to-node=\"9,0,0\" data-index-in-node=\"0\">\u0628\u0631\u0648\u062a\u064a\u0646:<\/b> 24 \u062c\u0631\u0627\u0645.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"9,1,0\"><b data-path-to-node=\"9,1,0\" data-index-in-node=\"0\">\u0627\u0644\u062f\u0647\u0648\u0646 \u0627\u0644\u0645\u0636\u0627\u0641\u0629:<\/b> \u0645\u0646\u062e\u0641\u0636\u0629 \u062c\u062f\u0627\u064b \u0645\u0639 \u062a\u0639\u0632\u064a\u0632 \u0628\u0640 <b data-path-to-node=\"9,1,0\" data-index-in-node=\"40\">MCT<\/b> (\u062f\u0647\u0648\u0646 \u0635\u062d\u064a\u0629 \u0644\u0644\u0637\u0627\u0642\u0629).<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"9,2,0\"><b data-path-to-node=\"9,2,0\" data-index-in-node=\"0\">\u0627\u0644\u0633\u0643\u0631 \u0627\u0644\u0645\u0636\u0627\u0641:<\/b> 0 \u062c\u0631\u0627\u0645.<\/p>\n<\/li>\n<\/ul>\n<h3 style=\"text-align: right\" data-path-to-node=\"10\"><b data-path-to-node=\"10\" data-index-in-node=\"0\">\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u062d\u0636\u064a\u0631 \u0648\u0627\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645:<\/b><\/h3>\n<p style=\"text-align: right\" data-path-to-node=\"11\">\u0644\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0645\u0634\u0631\u0648\u0628 \u0645\u062b\u0627\u0644\u064a \u0648\u062e\u0627\u0644\u064d \u0645\u0646 \u0627\u0644\u062a\u0643\u062a\u0644\u0627\u062a:<\/p>\n<ol style=\"text-align: right\" start=\"1\" data-path-to-node=\"12\">\n<li>\n<p data-path-to-node=\"12,0,0\"><b data-path-to-node=\"12,0,0\" data-index-in-node=\"0\">\u0627\u0644\u062e\u0644\u0637:<\/b> \u0623\u0636\u0641 \u0633\u0643\u0648\u0628 \u0648\u0627\u062d\u062f (35 \u062c\u0631\u0627\u0645) \u0625\u0644\u0649 150-200 \u0645\u0644 \u0645\u0646 \u0627\u0644\u0645\u0627\u0621 \u0627\u0644\u0628\u0627\u0631\u062f \u0623\u0648 \u0645\u0634\u0631\u0648\u0628\u0643 \u0627\u0644\u0645\u0641\u0636\u0644.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"12,1,0\"><b data-path-to-node=\"12,1,0\" data-index-in-node=\"0\">\u0627\u0644\u0631\u062c:<\/b> \u0627\u0633\u062a\u062e\u062f\u0645 \u0627\u0644\u0634\u064a\u0643\u0631 \u0648\u0642\u0645 \u0628\u0627\u0644\u0631\u062c \u062c\u064a\u062f\u0627\u064b \u0644\u0645\u062f\u0629 20-30 \u062b\u0627\u0646\u064a\u0629 \u062d\u062a\u0649 \u064a\u0630\u0648\u0628 \u062a\u0645\u0627\u0645\u0627\u064b.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"12,2,0\"><b data-path-to-node=\"12,2,0\" data-index-in-node=\"0\">\u0648\u0642\u062a \u0627\u0644\u062a\u0646\u0627\u0648\u0644:<\/b> \u064a\u064f\u0641\u0636\u0644 \u062a\u0646\u0627\u0648\u0644\u0647 \u0645\u0628\u0627\u0634\u0631\u0629 \u0628\u0639\u062f \u0627\u0644\u062a\u0645\u0631\u064a\u0646 \u0644\u062a\u062d\u0642\u064a\u0642 \u0623\u0642\u0635\u0649 \u0627\u0633\u062a\u0641\u0627\u062f\u0629\u060c \u0623\u0648 \u0641\u064a \u0623\u064a \u0648\u0642\u062a \u062e\u0644\u0627\u0644 \u0627\u0644\u064a\u0648\u0645 \u0644\u0632\u064a\u0627\u062f\u0629 \u062d\u0635\u062a\u0643 \u0627\u0644\u064a\u0648\u0645\u064a\u0629 \u0645\u0646 \u0627\u0644\u0628\u0631\u0648\u062a\u064a\u0646.<\/p>\n<\/li>\n<\/ol>\n<hr data-path-to-node=\"13\" \/>\n<h3 style=\"text-align: right\" data-path-to-node=\"14\"><b data-path-to-node=\"14\" data-index-in-node=\"0\">\u0627\u0644\u0645\u0643\u0648\u0646\u0627\u062a:<\/b><\/h3>\n<p style=\"text-align: right\" data-path-to-node=\"15\">\u0645\u0632\u064a\u062c \u0648\u0627\u064a \u0628\u0631\u0648\u062a\u064a\u0646 (\u0645\u0631\u0643\u0632\u060c \u0645\u0639\u0632\u0648\u0644\u060c \u0648\u0645\u062d\u0644\u0644)\u060c \u0645\u0633\u062d\u0648\u0642 \u0627\u0644\u0643\u0627\u0643\u0627\u0648\u060c \u0645\u0627\u0644\u062a\u0648\u062f\u064a\u0643\u0633\u062a\u0631\u064a\u0646\u060c \u0646\u0643\u0647\u0627\u062a\u060c \u0635\u0645\u063a \u0627\u0644\u0632\u0627\u0646\u062b\u0627\u0646\u060c \u0633\u0648\u0643\u0631\u0627\u0644\u0648\u0632\u060c \u0648\u062f\u0647\u0648\u0646 MCT.<\/p>\n<ul style=\"text-align: right\" data-path-to-node=\"16\">\n<li>\n<p data-path-to-node=\"16,0,0\"><b data-path-to-node=\"16,0,0\" data-index-in-node=\"0\">\u062a\u0646\u0628\u064a\u0647 \u0627\u0644\u062d\u0633\u0627\u0633\u064a\u0629:<\/b> \u064a\u062d\u062a\u0648\u064a \u0639\u0644\u0649 \u0627\u0644\u062d\u0644\u064a\u0628 \u0648\u0627\u0644\u0635\u0648\u064a\u0627.<\/p>\n<\/li>\n<\/ul>\n<hr data-path-to-node=\"17\" \/>\n<h3 style=\"text-align: right\" data-path-to-node=\"18\"><b data-path-to-node=\"18\" data-index-in-node=\"0\">\u062a\u062d\u0630\u064a\u0631\u0627\u062a \u0648\u0625\u0631\u0634\u0627\u062f\u0627\u062a \u0627\u0644\u0633\u0644\u0627\u0645\u0629:<\/b><\/h3>\n<ul data-path-to-node=\"19\">\n<li style=\"text-align: right\">\n<p data-path-to-node=\"19,0,0\">\u064a\u064f\u0633\u062a\u062e\u062f\u0645 \u0641\u0642\u0637 \u0645\u0646 \u0642\u0628\u0644 \u0627\u0644\u0628\u0627\u0644\u063a\u064a\u0646 \u0627\u0644\u0623\u0635\u062d\u0627\u0621 (18 \u0639\u0627\u0645\u0627\u064b \u0641\u0623\u0643\u062b\u0631).<\/p>\n<\/li>\n<li style=\"text-align: right\">\n<p data-path-to-node=\"19,1,0\">\u0644\u0627 \u064a\u064f\u0633\u062a\u062e\u062f\u0645 \u0641\u064a \u062d\u0627\u0644\u0627\u062a \u0627\u0644\u062d\u0645\u0644 \u0623\u0648 \u0627\u0644\u0631\u0636\u0627\u0639\u0629.<\/p>\n<\/li>\n<li style=\"text-align: right\">\n<p data-path-to-node=\"19,2,0\">\u0644\u0627 \u064a\u064f\u0633\u062a\u062e\u062f\u0645 \u0644\u0645\u0646 \u064a\u0639\u0627\u0646\u0648\u0646 \u0645\u0646 \u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0643\u0644\u0649\u060c \u0627\u0644\u0633\u0643\u0631\u064a\u060c \u0623\u0648 \u0627\u0644\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0645\u0632\u0645\u0646\u0629.<\/p>\n<\/li>\n<li style=\"text-align: right\">\n<p data-path-to-node=\"19,3,0\">\u063a\u064a\u0631 \u0645\u0646\u0627\u0633\u0628 \u0644\u0645\u0631\u0636\u0649 \u0627\u0644\u0641\u064a\u0646\u064a\u0644 \u0643\u064a\u062a\u0648\u0646\u0648\u0631\u064a\u0627 (Phenylketonuria).<\/p>\n<\/li>\n<li style=\"text-align: right\">\n<p data-path-to-node=\"19,4,0\">\u064a\u064f\u0646\u0635\u062d \u0628\u0634\u0631\u0628 \u0643\u0645\u064a\u0627\u062a \u0643\u0627\u0641\u064a\u0629 \u0645\u0646 \u0627\u0644\u0645\u0627\u0621 \u0637\u0648\u0627\u0644 \u0627\u0644\u064a\u0648\u0645 \u0623\u062b\u0646\u0627\u0621 \u0627\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645.<\/p>\n<\/li>\n<li>\n<p style=\"text-align: right\" data-path-to-node=\"19,5,0\">\u064a\u064f\u062d\u0641\u0638 \u0628\u0639\u064a\u062f\u0627\u064b \u0639\u0646 \u0645\u062a\u0646\u0627\u0648\u0644 \u0627\u0644\u0623\u0637\u0641\u0627\u0644 \u0641\u064a \u0645\u0643\u0627\u0646 \u0628\u0627\u0631\u062f \u0648\u062c\u0627\u0641.<\/p>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u0631\u0646 \u0623\u0644\u0648\u0646 \u0646\u0648\u062a\u0631\u064a\u0634\u0646 \u0648\u0627\u064a \u0631\u0646 (Run Alone Whey Run) 1.05 \u0643\u062c\u0645 | 30 \u062d\u0635\u0629 \u062a\u062f\u0631\u064a\u0628\u064a\u0629 | \u0646\u0643\u0647\u0629 \u0643\u0648\u0643\u0648 \u0628\u064a\u0633\u0643\u0648 (Coco<\/p>\n","protected":false},"featured_media":119652,"template":"","meta":[],"product_brand":[],"product_cat":[3969,2651,2590,2540],"product_tag":[],"class_list":["post-119645","product","type-product","status-publish","has-post-thumbnail","product_cat-protein-ar","product_cat-2651","product_cat-supplements-ar","product_cat-whey-protein-ar","pa_brands-run-alone-ar","pa_flavor-coco-bisco","pa_flavor-2714","pa_flavor-1660","pa_formation-1683","pa_origin-1685","pa_servings-30-","first","outofstock","sale","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.5 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0631\u0646 \u0623\u0644\u0648\u0646 \u0646\u0648\u062a\u0631\u064a\u0634\u0646 \u0648\u0627\u064a \u0631\u0646 - My Fitness Bag<\/title>\n<meta name=\"description\" content=\"Run Alone Pure Creatine with maximum absorption, promotes strength and increased muscle volume.A supply of pure creatine monohydrate for explosive power.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myfitnessbag.com\/ar\/product\/\u0631\u0646-\u0623\u0644\u0648\u0646-\u0646\u0648\u062a\u0631\u064a\u0634\u0646-\u0648\u0627\u064a-\u0631\u0646\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0631\u0646 \u0623\u0644\u0648\u0646 \u0646\u0648\u062a\u0631\u064a\u0634\u0646 \u0648\u0627\u064a \u0631\u0646\" \/>\n<meta property=\"og:description\" content=\"Run Alone Pure Creatine with maximum absorption, promotes strength and increased muscle volume.A supply of pure creatine monohydrate for explosive power.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myfitnessbag.com\/ar\/product\/\u0631\u0646-\u0623\u0644\u0648\u0646-\u0646\u0648\u062a\u0631\u064a\u0634\u0646-\u0648\u0627\u064a-\u0631\u0646\/\" \/>\n<meta property=\"og:site_name\" content=\"My Fitness Bag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myfitnessbag.eg\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T15:25:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/09\/background-12.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u062f\u0642\u064a\u0642\u062a\u0627\u0646\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/\",\"url\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/\",\"name\":\"\u0631\u0646 \u0623\u0644\u0648\u0646 \u0646\u0648\u062a\u0631\u064a\u0634\u0646 \u0648\u0627\u064a \u0631\u0646 - My Fitness Bag\",\"isPartOf\":{\"@id\":\"https:\/\/myfitnessbag.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/09\/background-12.png\",\"datePublished\":\"2025-09-25T18:15:54+00:00\",\"dateModified\":\"2026-04-27T15:25:22+00:00\",\"description\":\"Run Alone Pure Creatine with maximum absorption, promotes strength and increased muscle volume.A supply of pure creatine monohydrate for explosive power.\",\"breadcrumb\":{\"@id\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/#primaryimage\",\"url\":\"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/09\/background-12.png\",\"contentUrl\":\"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/09\/background-12.png\",\"width\":500,\"height\":500,\"caption\":\"Run Alone Nutrition Whey Run 1.05kg, 30 Servings\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/myfitnessbag.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0644\u0645\u062a\u062c\u0631\",\"item\":\"https:\/\/myfitnessbag.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0631\u0646 \u0623\u0644\u0648\u0646 \u0646\u0648\u062a\u0631\u064a\u0634\u0646 \u0648\u0627\u064a \u0631\u0646\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/myfitnessbag.com\/#website\",\"url\":\"https:\/\/myfitnessbag.com\/\",\"name\":\"My Fitness Bag\",\"description\":\"Egypt&#039;s #1 Sports Nutrition &amp; Fitness Store\",\"publisher\":{\"@id\":\"https:\/\/myfitnessbag.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/myfitnessbag.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/myfitnessbag.com\/#organization\",\"name\":\"My Fitness Bag\",\"url\":\"https:\/\/myfitnessbag.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/myfitnessbag.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/03\/1.png\",\"contentUrl\":\"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/03\/1.png\",\"width\":1500,\"height\":1500,\"caption\":\"My Fitness Bag\"},\"image\":{\"@id\":\"https:\/\/myfitnessbag.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/myfitnessbag.eg\/\",\"https:\/\/www.instagram.com\/myfitnessbag.eg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0631\u0646 \u0623\u0644\u0648\u0646 \u0646\u0648\u062a\u0631\u064a\u0634\u0646 \u0648\u0627\u064a \u0631\u0646 - My Fitness Bag","description":"Run Alone Pure Creatine with maximum absorption, promotes strength and increased muscle volume.A supply of pure creatine monohydrate for explosive power.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myfitnessbag.com\/ar\/product\/\u0631\u0646-\u0623\u0644\u0648\u0646-\u0646\u0648\u062a\u0631\u064a\u0634\u0646-\u0648\u0627\u064a-\u0631\u0646\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0631\u0646 \u0623\u0644\u0648\u0646 \u0646\u0648\u062a\u0631\u064a\u0634\u0646 \u0648\u0627\u064a \u0631\u0646","og_description":"Run Alone Pure Creatine with maximum absorption, promotes strength and increased muscle volume.A supply of pure creatine monohydrate for explosive power.","og_url":"https:\/\/myfitnessbag.com\/ar\/product\/\u0631\u0646-\u0623\u0644\u0648\u0646-\u0646\u0648\u062a\u0631\u064a\u0634\u0646-\u0648\u0627\u064a-\u0631\u0646\/","og_site_name":"My Fitness Bag","article_publisher":"https:\/\/www.facebook.com\/myfitnessbag.eg\/","article_modified_time":"2026-04-27T15:25:22+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/09\/background-12.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"\u062f\u0642\u064a\u0642\u062a\u0627\u0646"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/","url":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/","name":"\u0631\u0646 \u0623\u0644\u0648\u0646 \u0646\u0648\u062a\u0631\u064a\u0634\u0646 \u0648\u0627\u064a \u0631\u0646 - My Fitness Bag","isPartOf":{"@id":"https:\/\/myfitnessbag.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/#primaryimage"},"image":{"@id":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/#primaryimage"},"thumbnailUrl":"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/09\/background-12.png","datePublished":"2025-09-25T18:15:54+00:00","dateModified":"2026-04-27T15:25:22+00:00","description":"Run Alone Pure Creatine with maximum absorption, promotes strength and increased muscle volume.A supply of pure creatine monohydrate for explosive power.","breadcrumb":{"@id":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/#primaryimage","url":"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/09\/background-12.png","contentUrl":"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/09\/background-12.png","width":500,"height":500,"caption":"Run Alone Nutrition Whey Run 1.05kg, 30 Servings"},{"@type":"BreadcrumbList","@id":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%b1%d9%86-%d8%a3%d9%84%d9%88%d9%86-%d9%86%d9%88%d8%aa%d8%b1%d9%8a%d8%b4%d9%86-%d9%88%d8%a7%d9%8a-%d8%b1%d9%86\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/myfitnessbag.com\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u0645\u062a\u062c\u0631","item":"https:\/\/myfitnessbag.com\/shop\/"},{"@type":"ListItem","position":3,"name":"\u0631\u0646 \u0623\u0644\u0648\u0646 \u0646\u0648\u062a\u0631\u064a\u0634\u0646 \u0648\u0627\u064a \u0631\u0646"}]},{"@type":"WebSite","@id":"https:\/\/myfitnessbag.com\/#website","url":"https:\/\/myfitnessbag.com\/","name":"My Fitness Bag","description":"Egypt&#039;s #1 Sports Nutrition &amp; Fitness Store","publisher":{"@id":"https:\/\/myfitnessbag.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/myfitnessbag.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/myfitnessbag.com\/#organization","name":"My Fitness Bag","url":"https:\/\/myfitnessbag.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/myfitnessbag.com\/#\/schema\/logo\/image\/","url":"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/03\/1.png","contentUrl":"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/03\/1.png","width":1500,"height":1500,"caption":"My Fitness Bag"},"image":{"@id":"https:\/\/myfitnessbag.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myfitnessbag.eg\/","https:\/\/www.instagram.com\/myfitnessbag.eg"]}]}},"_links":{"self":[{"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/product\/119645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/product\/119645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/media\/119652"}],"wp:attachment":[{"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/media?parent=119645"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/product_brand?post=119645"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/product_cat?post=119645"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/product_tag?post=119645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}