{"id":145558,"date":"2026-04-27T16:59:59","date_gmt":"2026-04-27T13:59:59","guid":{"rendered":"https:\/\/myfitnessbag.com\/?post_type=product&#038;p=145558"},"modified":"2026-04-27T17:07:36","modified_gmt":"2026-04-27T14:07:36","slug":"%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1","status":"publish","type":"product","link":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/","title":{"rendered":"\u062d\u0630\u0627\u0621 \u0623\u062f\u064a\u062f\u0627\u0633RAPIDMOVE ADV 2 \u0644\u0644\u0646\u0633\u0627\u0621"},"content":{"rendered":"<div class=\"product-details__block\">\n<h1 style=\"text-align: right\" data-path-to-node=\"0\">\u062d\u0630\u0627\u0621 \u0623\u062f\u064a\u062f\u0627\u0633RAPIDMOVE ADV 2 \u0644\u0644\u0646\u0633\u0627\u0621<\/h1>\n<h1 style=\"text-align: right\" data-path-to-node=\"0\"><span style=\"font-size: 16px\">\u0623\u0637\u0644\u0642\u0650 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u064a\u0648\u0646\u0629 \u0648\u0627\u0644\u0631\u0634\u0627\u0642\u0629 \u0645\u0639 \u062d\u0630\u0627\u0621 \u0627\u0644\u062a\u062f\u0631\u064a\u0628 <\/span><b style=\"font-size: 16px\" data-path-to-node=\"0\" data-index-in-node=\"45\">RAPIDMOVE ADV 2 W<\/b><span style=\"font-size: 16px\">. \u0635\u064f\u0645\u0645 \u0647\u0630\u0627 \u0627\u0644\u062d\u0630\u0627\u0621 \u062e\u0635\u064a\u0635\u0627\u064b \u0644\u0644\u0633\u064a\u062f\u0627\u062a \u0627\u0644\u0634\u063a\u0648\u0641\u0627\u062a \u0628\u062a\u0645\u0627\u0631\u064a\u0646 \u0627\u0644\u0640 <\/span><b style=\"font-size: 16px\" data-path-to-node=\"0\" data-index-in-node=\"116\">HIIT<\/b><span style=\"font-size: 16px\"> \u0648\u062d\u0635\u0635 \u0627\u0644\u062c\u064a\u0645\u060c \u062d\u064a\u062b \u064a\u0648\u0641\u0631 \u0627\u0633\u062a\u0642\u0631\u0627\u0631\u0627\u064b \u062f\u064a\u0646\u0627\u0645\u064a\u0643\u064a\u0627\u064b \u0648\u0627\u0633\u062a\u062c\u0627\u0628\u0629 \u0641\u0627\u0626\u0642\u0629 \u0641\u064a \u062c\u0645\u064a\u0639 \u0627\u0644\u0627\u062a\u062c\u0627\u0647\u0627\u062a.<\/span><\/h1>\n<div>\n<div class=\"response-container response-container-with-gpi ng-tns-c3415320510-11 no-background response-container-has-multiple-responses\" data-hveid=\"1\">\n<div class=\"presented-response-container ng-tns-c3415320510-11\" data-hveid=\"3\">\n<div class=\"response-container-content ng-tns-c3415320510-11\">\n<div class=\"response-content ng-tns-c3415320510-11\">\n<div class=\"container\">\n<div id=\"model-response-message-contentr_d6adca9601947311\" class=\"markdown markdown-main-panel stronger enable-updated-hr-color\" dir=\"rtl\" aria-live=\"polite\">\n<hr data-path-to-node=\"1\" \/>\n<h3 data-path-to-node=\"2\"><b data-path-to-node=\"2\" data-index-in-node=\"0\">\u0627\u0644\u0645\u0645\u064a\u0632\u0627\u062a \u0627\u0644\u062a\u0642\u0646\u064a\u0629:<\/b><\/h3>\n<ul data-path-to-node=\"3\">\n<li>\n<p data-path-to-node=\"3,0,0\"><b data-path-to-node=\"3,0,0\" data-index-in-node=\"0\">\u0627\u0644\u062c\u0632\u0621 \u0627\u0644\u0639\u0644\u0648\u064a:<\/b> \u0645\u0635\u0646\u0648\u0639 \u0645\u0646 \u0627\u0644\u0634\u0628\u0643 (Mesh) \u0644\u0636\u0645\u0627\u0646 \u062a\u0647\u0648\u064a\u0629 \u062e\u0641\u064a\u0641\u0629 \u0627\u0644\u0648\u0632\u0646\u060c \u0645\u0639 \u0637\u0628\u0642\u0627\u062a \u0645\u0646 \u0627\u0644\u0640 <b data-path-to-node=\"3,0,0\" data-index-in-node=\"77\">TPU<\/b> \u0644\u062a\u0639\u0632\u064a\u0632 \u0627\u0644\u0645\u062a\u0627\u0646\u0629.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"3,1,0\"><b data-path-to-node=\"3,1,0\" data-index-in-node=\"0\">\u0646\u0638\u0627\u0645 \u0627\u0644\u0631\u0628\u0637:<\/b> \u0623\u0631\u0628\u0637\u0629 \u0642\u0627\u0628\u0644\u0629 \u0644\u0644\u062a\u0639\u062f\u064a\u0644 \u062a\u0636\u0645\u0646 \u0625\u062d\u0643\u0627\u0645\u0627\u064b \u0645\u062e\u0635\u0635\u0627\u064b \u0648\u0645\u062b\u0627\u0644\u064a\u0629 \u0644\u062b\u0628\u0627\u062a \u0642\u062f\u0645\u0643\u0650.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"3,2,0\"><b data-path-to-node=\"3,2,0\" data-index-in-node=\"0\">\u0646\u0639\u0644 \u0623\u0648\u0633\u0637 \u0645\u062a\u0637\u0648\u0631:<\/b> \u062c\u0631\u0628\u064a \u062a\u0648\u0633\u064a\u062f\u0627\u064b \u0641\u0627\u0626\u0642\u0627\u064b \u0648\u0627\u0631\u062a\u062f\u0627\u062f\u0627\u064b \u0645\u0645\u062a\u0627\u0632\u0627\u064b \u0644\u0644\u0637\u0627\u0642\u0629 \u0628\u0641\u0636\u0644 \u062a\u0642\u0646\u064a\u062a\u064a <b data-path-to-node=\"3,2,0\" data-index-in-node=\"73\">LIGHTSTRIKE<\/b> \u0648 <b data-path-to-node=\"3,2,0\" data-index-in-node=\"87\">LIGHTSTRIKE PRO<\/b>.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"3,3,0\"><b data-path-to-node=\"3,3,0\" data-index-in-node=\"0\">\u0627\u0644\u062b\u0628\u0627\u062a \u0648\u0627\u0644\u062a\u062d\u0643\u0645:<\/b> \u064a\u0636\u0645\u0646 \u0627\u0644\u0646\u0639\u0644 \u0627\u0644\u062e\u0627\u0631\u062c\u064a \u0627\u0644\u0645\u0635\u0646\u0648\u0639 \u0645\u0646 \u0645\u0637\u0627\u0637 <b data-path-to-node=\"3,3,0\" data-index-in-node=\"51\">Continental\u2122<\/b> \u062b\u0628\u0627\u062a\u0627\u064b \u0627\u0633\u062a\u062b\u0646\u0627\u0626\u064a\u0627\u064b \u0639\u0644\u0649 \u0627\u0644\u0623\u0631\u0636 \u0623\u062b\u0646\u0627\u0621 \u0627\u0644\u062d\u0631\u0643\u0627\u062a \u0645\u062a\u0639\u062f\u062f\u0629 \u0627\u0644\u0627\u062a\u062c\u0627\u0647\u0627\u062a.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"3,4,0\"><b data-path-to-node=\"3,4,0\" data-index-in-node=\"0\">\u0627\u0644\u0627\u0633\u062a\u062f\u0627\u0645\u0629:<\/b> \u0635\u064f\u0646\u0639 \u0647\u0630\u0627 \u0627\u0644\u062d\u0630\u0627\u0621 \u062c\u0632\u0626\u064a\u0627\u064b \u0645\u0646 \u0645\u0648\u0627\u062f \u0645\u0639\u0627\u062f \u062a\u062f\u0648\u064a\u0631\u0647\u0627\u060c \u0645\u0645\u0627 \u064a\u062c\u0639\u0644\u0647 \u062e\u064a\u0627\u0631\u0627\u064b \u0645\u0633\u062a\u062f\u0627\u0645\u0627\u064b \u0644\u062c\u0644\u0633\u0627\u062a\u0643\u0650 \u0627\u0644\u062a\u062f\u0631\u064a\u0628\u064a\u0629.<\/p>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u062d\u0630\u0627\u0621 \u0623\u062f\u064a\u062f\u0627\u0633RAPIDMOVE ADV 2 \u0644\u0644\u0646\u0633\u0627\u0621 \u0623\u0637\u0644\u0642\u0650 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u064a\u0648\u0646\u0629 \u0648\u0627\u0644\u0631\u0634\u0627\u0642\u0629 \u0645\u0639 \u062d\u0630\u0627\u0621 \u0627\u0644\u062a\u062f\u0631\u064a\u0628 RAPIDMOVE ADV 2 W. \u0635\u064f\u0645\u0645 \u0647\u0630\u0627 \u0627\u0644\u062d\u0630\u0627\u0621 \u062e\u0635\u064a\u0635\u0627\u064b<\/p>\n","protected":false},"featured_media":145561,"template":"","meta":[],"product_brand":[],"product_cat":[2822,2643],"product_tag":[],"class_list":["post-145558","product","type-product","status-publish","has-post-thumbnail","product_cat-2822","product_cat-2643","pa_brands-adidas","first","instock","sale","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.5 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u062d\u0630\u0627\u0621 \u0623\u062f\u064a\u062f\u0627\u0633RAPIDMOVE ADV 2 \u0644\u0644\u0646\u0633\u0627\u0621 - My Fitness Bag<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myfitnessbag.com\/ar\/product\/\u062d\u0630\u0627\u0621-\u0623\u062f\u064a\u062f\u0627\u0633rapidmove-adv-2-\u0644\u0644\u0646\u0633\u0627\u0621\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062d\u0630\u0627\u0621 \u0623\u062f\u064a\u062f\u0627\u0633RAPIDMOVE ADV 2 \u0644\u0644\u0646\u0633\u0627\u0621\" \/>\n<meta property=\"og:description\" content=\"\u062d\u0630\u0627\u0621 \u0623\u062f\u064a\u062f\u0627\u0633RAPIDMOVE ADV 2 \u0644\u0644\u0646\u0633\u0627\u0621 \u0623\u0637\u0644\u0642\u0650 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u064a\u0648\u0646\u0629 \u0648\u0627\u0644\u0631\u0634\u0627\u0642\u0629 \u0645\u0639 \u062d\u0630\u0627\u0621 \u0627\u0644\u062a\u062f\u0631\u064a\u0628 RAPIDMOVE ADV 2 W. \u0635\u064f\u0645\u0645 \u0647\u0630\u0627 \u0627\u0644\u062d\u0630\u0627\u0621 \u062e\u0635\u064a\u0635\u0627\u064b\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myfitnessbag.com\/ar\/product\/\u062d\u0630\u0627\u0621-\u0623\u062f\u064a\u062f\u0627\u0633rapidmove-adv-2-\u0644\u0644\u0646\u0633\u0627\u0621\/\" \/>\n<meta property=\"og:site_name\" content=\"My Fitness Bag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myfitnessbag.eg\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T14:07:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2026\/04\/JS3171-1-FOOTWEAR-Photography-Side-Lateral-Center-View-white.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u062f\u0642\u064a\u0642\u0629\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/\",\"url\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/\",\"name\":\"\u062d\u0630\u0627\u0621 \u0623\u062f\u064a\u062f\u0627\u0633RAPIDMOVE ADV 2 \u0644\u0644\u0646\u0633\u0627\u0621 - My Fitness Bag\",\"isPartOf\":{\"@id\":\"https:\/\/myfitnessbag.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2026\/04\/JS3171-1-FOOTWEAR-Photography-Side-Lateral-Center-View-white.webp\",\"datePublished\":\"2026-04-27T13:59:59+00:00\",\"dateModified\":\"2026-04-27T14:07:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/#primaryimage\",\"url\":\"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2026\/04\/JS3171-1-FOOTWEAR-Photography-Side-Lateral-Center-View-white.webp\",\"contentUrl\":\"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2026\/04\/JS3171-1-FOOTWEAR-Photography-Side-Lateral-Center-View-white.webp\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/myfitnessbag.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0644\u0645\u062a\u062c\u0631\",\"item\":\"https:\/\/myfitnessbag.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u062d\u0630\u0627\u0621 \u0623\u062f\u064a\u062f\u0627\u0633RAPIDMOVE ADV 2 \u0644\u0644\u0646\u0633\u0627\u0621\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/myfitnessbag.com\/#website\",\"url\":\"https:\/\/myfitnessbag.com\/\",\"name\":\"My Fitness Bag\",\"description\":\"Egypt&#039;s #1 Sports Nutrition &amp; Fitness Store\",\"publisher\":{\"@id\":\"https:\/\/myfitnessbag.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/myfitnessbag.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/myfitnessbag.com\/#organization\",\"name\":\"My Fitness Bag\",\"url\":\"https:\/\/myfitnessbag.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/myfitnessbag.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/03\/1.png\",\"contentUrl\":\"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/03\/1.png\",\"width\":1500,\"height\":1500,\"caption\":\"My Fitness Bag\"},\"image\":{\"@id\":\"https:\/\/myfitnessbag.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/myfitnessbag.eg\/\",\"https:\/\/www.instagram.com\/myfitnessbag.eg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u062d\u0630\u0627\u0621 \u0623\u062f\u064a\u062f\u0627\u0633RAPIDMOVE ADV 2 \u0644\u0644\u0646\u0633\u0627\u0621 - My Fitness Bag","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myfitnessbag.com\/ar\/product\/\u062d\u0630\u0627\u0621-\u0623\u062f\u064a\u062f\u0627\u0633rapidmove-adv-2-\u0644\u0644\u0646\u0633\u0627\u0621\/","og_locale":"ar_AR","og_type":"article","og_title":"\u062d\u0630\u0627\u0621 \u0623\u062f\u064a\u062f\u0627\u0633RAPIDMOVE ADV 2 \u0644\u0644\u0646\u0633\u0627\u0621","og_description":"\u062d\u0630\u0627\u0621 \u0623\u062f\u064a\u062f\u0627\u0633RAPIDMOVE ADV 2 \u0644\u0644\u0646\u0633\u0627\u0621 \u0623\u0637\u0644\u0642\u0650 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u064a\u0648\u0646\u0629 \u0648\u0627\u0644\u0631\u0634\u0627\u0642\u0629 \u0645\u0639 \u062d\u0630\u0627\u0621 \u0627\u0644\u062a\u062f\u0631\u064a\u0628 RAPIDMOVE ADV 2 W. \u0635\u064f\u0645\u0645 \u0647\u0630\u0627 \u0627\u0644\u062d\u0630\u0627\u0621 \u062e\u0635\u064a\u0635\u0627\u064b","og_url":"https:\/\/myfitnessbag.com\/ar\/product\/\u062d\u0630\u0627\u0621-\u0623\u062f\u064a\u062f\u0627\u0633rapidmove-adv-2-\u0644\u0644\u0646\u0633\u0627\u0621\/","og_site_name":"My Fitness Bag","article_publisher":"https:\/\/www.facebook.com\/myfitnessbag.eg\/","article_modified_time":"2026-04-27T14:07:36+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2026\/04\/JS3171-1-FOOTWEAR-Photography-Side-Lateral-Center-View-white.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"1 \u062f\u0642\u064a\u0642\u0629"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/","url":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/","name":"\u062d\u0630\u0627\u0621 \u0623\u062f\u064a\u062f\u0627\u0633RAPIDMOVE ADV 2 \u0644\u0644\u0646\u0633\u0627\u0621 - My Fitness Bag","isPartOf":{"@id":"https:\/\/myfitnessbag.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/#primaryimage"},"image":{"@id":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/#primaryimage"},"thumbnailUrl":"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2026\/04\/JS3171-1-FOOTWEAR-Photography-Side-Lateral-Center-View-white.webp","datePublished":"2026-04-27T13:59:59+00:00","dateModified":"2026-04-27T14:07:36+00:00","breadcrumb":{"@id":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/#primaryimage","url":"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2026\/04\/JS3171-1-FOOTWEAR-Photography-Side-Lateral-Center-View-white.webp","contentUrl":"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2026\/04\/JS3171-1-FOOTWEAR-Photography-Side-Lateral-Center-View-white.webp","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/myfitnessbag.com\/ar\/product\/%d8%ad%d8%b0%d8%a7%d8%a1-%d8%a3%d8%af%d9%8a%d8%af%d8%a7%d8%b3rapidmove-adv-2-%d9%84%d9%84%d9%86%d8%b3%d8%a7%d8%a1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/myfitnessbag.com\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u0645\u062a\u062c\u0631","item":"https:\/\/myfitnessbag.com\/shop\/"},{"@type":"ListItem","position":3,"name":"\u062d\u0630\u0627\u0621 \u0623\u062f\u064a\u062f\u0627\u0633RAPIDMOVE ADV 2 \u0644\u0644\u0646\u0633\u0627\u0621"}]},{"@type":"WebSite","@id":"https:\/\/myfitnessbag.com\/#website","url":"https:\/\/myfitnessbag.com\/","name":"My Fitness Bag","description":"Egypt&#039;s #1 Sports Nutrition &amp; Fitness Store","publisher":{"@id":"https:\/\/myfitnessbag.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/myfitnessbag.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/myfitnessbag.com\/#organization","name":"My Fitness Bag","url":"https:\/\/myfitnessbag.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/myfitnessbag.com\/#\/schema\/logo\/image\/","url":"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/03\/1.png","contentUrl":"https:\/\/myfitnessbag.com\/wp-content\/uploads\/2025\/03\/1.png","width":1500,"height":1500,"caption":"My Fitness Bag"},"image":{"@id":"https:\/\/myfitnessbag.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myfitnessbag.eg\/","https:\/\/www.instagram.com\/myfitnessbag.eg"]}]}},"_links":{"self":[{"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/product\/145558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/product\/145558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/media\/145561"}],"wp:attachment":[{"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/media?parent=145558"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/product_brand?post=145558"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/product_cat?post=145558"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/myfitnessbag.com\/ar\/wp-json\/wp\/v2\/product_tag?post=145558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}